{"id":13006,"date":"2022-12-05T16:44:58","date_gmt":"2022-12-05T15:44:58","guid":{"rendered":"https:\/\/cc.markeasy.lu\/schulung-zur-kohlenstofffreien-mobilitaet-fuer-unsere-mieter-die-wichtigsten-erkenntnisse\/"},"modified":"2022-12-05T16:44:58","modified_gmt":"2022-12-05T15:44:58","slug":"schulung-zur-kohlenstofffreien-mobilitaet-fuer-unsere-mieter-die-wichtigsten-erkenntnisse","status":"publish","type":"post","link":"https:\/\/campuscontern.lu\/de\/aktuelles\/schulung-zur-kohlenstofffreien-mobilitaet-fuer-unsere-mieter-die-wichtigsten-erkenntnisse\/","title":{"rendered":"Schulung zur kohlenstofffreien Mobilit\u00e4t f\u00fcr unsere Mieter: Die wichtigsten Erkenntnisse"},"content":{"rendered":"<p>Letzte Woche fand die erste Schulung \u201eStreben nach Kohlenstoffneutralit\u00e4t durch Mobilit\u00e4tsmanagement\u201c mit Luxmobility, Carbone 4, EIT Urban Mobility und IMS statt. Wir haben uns entschieden, unsere Mieter zur Teilnahme einzuladen. <\/p>\n<p>Hier sind die wichtigsten Punkte und Erkenntnisse, die wir daraus gewonnen haben:<\/p>\n<p>&nbsp;<\/p>\n<h2>Einige aussagekr\u00e4ftige Zahlen:<\/h2>\n<p><strong>Der durchschnittliche CO2-Fu\u00dfabdruck eines Luxemburgers betr\u00e4gt 16 t CO2 pro Jahr<\/strong> &#8230; w\u00e4hrend der Schwellenwert zur Erreichung der Ziele idealerweise 2 t CO2 pro Jahr betr\u00e4gt.<\/p>\n<p><strong>Die Mobilit\u00e4t macht 17 %<\/strong> des Luxemburger CO2-Fu\u00dfabdrucks aus.<\/p>\n<p>Die Reduzierung der Autogr\u00f6\u00dfe kann zu <strong>60 % Emissionseinsparungen<\/strong> f\u00fchren<\/p>\n<p>Der Umstieg von Verbrennern auf Elektrofahrzeuge kann die Emissionen um bis zu 70 % reduzieren (inklusive Herstellung)<\/p>\n<p>Zugfahren bedeutet <strong>95 % weniger Emissionen<\/strong> als Autofahren!<\/p>\n<p>In Luxemburg <strong>ist die Nutzung des Fahrrads in 2 Jahren von 2 % auf 5 % gestiegen<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<h2>Am wichtigsten ist das Handeln<\/h2>\n<p>Der Klimawandel ist da, und wir m\u00fcssen uns anpassen, indem wir unseren Einfluss und den Einfluss unserer Aktivit\u00e4ten auf unsere Ressourcen so weit wie m\u00f6glich reduzieren.<\/p>\n<p>Man muss verstehen, dass <strong>die Schuldzuweisung und der Vorwurf an den Nachbarn, nichts zu tun, nichts zur Bew\u00e4ltigung beitr\u00e4gt<\/strong>: +5\u00b0 bedeuten physische Risiken f\u00fcr den Menschen und seinen Lebensraum (also uns!) sowie \u00dcbergangsrisiken (Politik, Steuern, Regulierung etc.).<\/p>\n<p>Die CO2-Bilanz ist nur ein Indikator f\u00fcr Abh\u00e4ngigkeit. Sie dient dazu, unsere Abh\u00e4ngigkeit von den Elementen zu messen und ist ein integraler Bestandteil der ersten Phase des Handelns: <\/p>\n<p>1 \/ <strong>Messen<\/strong>! Man kann nicht auf etwas einwirken, das man nicht kennt.<\/p>\n<p>2 \/ <strong>Engagieren<\/strong> Sie sich unter Einbeziehung aller internen und externen Stakeholder des Unternehmens. Besonders die Gesch\u00e4ftsleitung: Die Unterst\u00fctzung der Gesch\u00e4ftsleitung ist notwendig, damit sich etwas bewegt. <\/p>\n<p>3 \/ <strong>Handeln<\/strong>: konkrete und messbare Ma\u00dfnahmen, um wirklich positiv zu wirken. Zum Beispiel: <\/p>\n<blockquote><p><em>Bevor man mehr B\u00e4ume pflanzt, muss man zuerst aufh\u00f6ren, sie zu f\u00e4llen. Das klingt einfach, aber darin liegt die ganze Herausforderung.  <strong>Der Beitrag ist viel wirkungsvoller als die Kompensation! <\/strong> erkl\u00e4rt uns Christina Stuart von Carbone 4<\/em><\/p><\/blockquote>\n<p>&nbsp;<\/p>\n<h2>Und in Bezug auf Mobilit\u00e4t?<\/h2>\n<blockquote><p><em>Die Mobilit\u00e4t muss an unsere Bed\u00fcrfnisse angepasst werden, erkl\u00e4rt Patrick Van Egmond, manchmal f\u00e4hrt man nur ins B\u00fcro und zur\u00fcck, und manchmal muss man einkaufen, die Kinder abholen usw., was die Nutzung von Autoalternativen erschwert. <\/em><\/p><\/blockquote>\n<p>Was man auch beachten sollte, ist, dass <strong>Fahrgemeinschaften bilden, \u00f6ffentliche Verkehrsmittel oder das Fahrrad nutzen, selbst einen Tag pro Woche, erhebliche Auswirkungen hat <\/strong>!<\/p>\n<p>Der durchschnittliche Pendler-Fu\u00dfabdruck in Luxemburg betr\u00e4gt 1710 kg CO2e\/Person\/Jahr, er sinkt auf 1420, wenn man die Fahrgemeinschaften von 1,2 auf 1,6 Personen pro Fahrzeug erh\u00f6ht!<\/p>\n<p>Deshalb ist der Mobilit\u00e4tsplan f\u00fcr Unternehmen n\u00fctzlich. Er erm\u00f6glicht es, m\u00f6gliche Synergien zu erkennen, Optimierungsm\u00f6glichkeiten f\u00fcr jeden zu identifizieren und Mitarbeitern sowie der Personalabteilung Ideen zu geben, um das Mobilit\u00e4tsbudget \u00fcber das reine Fahrzeugleasing hinaus zu optimieren. <\/p>\n<p>Das Mobilit\u00e4ts-Fresko ist ein gutes Instrument zur Sensibilisierung und liefert die Grundlagen und Handlungshebel:<\/p>\n<ul>\n<li>Das Auto sparsam nutzen (zum Beispiel ein Familienauto verschmutzt fast 3-mal weniger als ein SUV!)<\/li>\n<li>Verkehrsmittel wechseln (der Zug ist 95 % sauberer als das Auto)<\/li>\n<li>K\u00fcrzere Wege zur\u00fccklegen (ein Paris-New York-Flug sind 2 t CO2, was unserem gesamten idealen Jahreskontingent entspricht)<\/li>\n<li>Sich seltener bewegen<\/li>\n<\/ul>\n<h2>Die Mobilit\u00e4tsvorteile von Campus Contern<\/h2>\n<p>Diese Schulung war auch eine Gelegenheit zu sehen, dass viele Initiativen in unseren B\u00fcros in die richtige Richtung gehen:<\/p>\n<ul>\n<li>Der Shuttle-Service, der den Bahnhof mit dem B\u00fcro verbindet,<\/li>\n<li>Das Carsharing,<\/li>\n<li>Die Fahrradparkpl\u00e4tze<\/li>\n<li>Die 128 Ladestationen<\/li>\n<li>Die Fahrgemeinschaften<\/li>\n<\/ul>\n<p>All diese Zutaten, die sanftere Mobilit\u00e4tsoptionen erm\u00f6glichen. Unser Mobilit\u00e4tsplan wird derzeit umgesetzt, wir werden sehen, welche weiteren Ma\u00dfnahmen wir ergreifen k\u00f6nnen, um das Beste f\u00fcr unsere Gemeinschaft zu tun. <\/p>\n<p>Herzlichen Dank an unsere Mieter f\u00fcr ihre Teilnahme und an die verschiedenen Referenten.<\/p>\n<p>&nbsp;<\/p>\n<h3>Ressourcen:<\/h3>\n<p>Luxmobility f\u00fcr den Zugang zu dieser Schulung <a href=\"https:\/\/luxmobility.eu\/\">https:\/\/luxmobility.eu\/<\/a><\/p>\n<p>EIT Urban Mobility bietet Schulungen und <strong>kostenlose Erkl\u00e4rvideos<\/strong> auf <a href=\"https:\/\/urbanmobilitycourses.eu\/\">https:\/\/urbanmobilitycourses.eu\/<\/a> an (die \u201eApplied\u201c-Schulungen sind kostenpflichtig, da sie personalisiert sind, aber alles andere ist frei zug\u00e4nglich).<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Letzte Woche fand die erste Schulung \u201eStreben nach Kohlenstoffneutralit\u00e4t durch Mobilit\u00e4tsmanagement\u201c mit Luxmobility, Carbone 4, EIT Urban Mobility und IMS statt. Wir haben uns entschieden, unsere Mieter zur Teilnahme einzuladen. Hier sind die wichtigsten Punkte und Erkenntnisse, die wir daraus gewonnen haben: &nbsp; Einige aussagekr\u00e4ftige Zahlen: Der durchschnittliche CO2-Fu\u00dfabdruck eines Luxemburgers betr\u00e4gt 16 t CO2 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":13007,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","ocean_post_oembed":"","ocean_post_self_hosted_media":"","ocean_post_video_embed":"","ocean_link_format":"","ocean_link_format_target":"self","ocean_quote_format":"","ocean_quote_format_link":"post","ocean_gallery_link_images":"on","ocean_gallery_id":[],"footnotes":""},"categories":[254],"tags":[],"class_list":["post-13006","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelles","entry","has-media"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Schulung zur kohlenstofffreien Mobilit\u00e4t f\u00fcr unsere Mieter: Die wichtigsten Erkenntnisse - Campus Contern<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schulung zur kohlenstofffreien Mobilit\u00e4t f\u00fcr unsere Mieter: Die wichtigsten Erkenntnisse - Campus Contern\" \/>\n<meta property=\"og:description\" content=\"Letzte Woche fand die erste Schulung \u201eStreben nach Kohlenstoffneutralit\u00e4t durch Mobilit\u00e4tsmanagement\u201c mit Luxmobility, Carbone 4, EIT Urban Mobility und IMS statt. Wir haben uns entschieden, unsere Mieter zur Teilnahme einzuladen. Hier sind die wichtigsten Punkte und Erkenntnisse, die wir daraus gewonnen haben: &nbsp; Einige aussagekr\u00e4ftige Zahlen: Der durchschnittliche CO2-Fu\u00dfabdruck eines Luxemburgers betr\u00e4gt 16 t CO2 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/campuscontern.lu\/de\/aktuelles\/schulung-zur-kohlenstofffreien-mobilitaet-fuer-unsere-mieter-die-wichtigsten-erkenntnisse\/\" \/>\n<meta property=\"og:site_name\" content=\"Campus Contern\" \/>\n<meta property=\"article:published_time\" content=\"2022-12-05T15:44:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/campuscontern.lu\/wp-content\/uploads\/2026\/04\/etiquette_article-3-2.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"628\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/campuscontern.lu\\\/de\\\/aktuelles\\\/schulung-zur-kohlenstofffreien-mobilitaet-fuer-unsere-mieter-die-wichtigsten-erkenntnisse\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campuscontern.lu\\\/de\\\/aktuelles\\\/schulung-zur-kohlenstofffreien-mobilitaet-fuer-unsere-mieter-die-wichtigsten-erkenntnisse\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/campuscontern.lu\\\/de\\\/#\\\/schema\\\/person\\\/462336658fc158f425b7b47a82ece390\"},\"headline\":\"Schulung zur kohlenstofffreien Mobilit\u00e4t f\u00fcr unsere Mieter: Die wichtigsten Erkenntnisse\",\"datePublished\":\"2022-12-05T15:44:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/campuscontern.lu\\\/de\\\/aktuelles\\\/schulung-zur-kohlenstofffreien-mobilitaet-fuer-unsere-mieter-die-wichtigsten-erkenntnisse\\\/\"},\"wordCount\":677,\"image\":{\"@id\":\"https:\\\/\\\/campuscontern.lu\\\/de\\\/aktuelles\\\/schulung-zur-kohlenstofffreien-mobilitaet-fuer-unsere-mieter-die-wichtigsten-erkenntnisse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campuscontern.lu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/etiquette_article-3-2.png\",\"articleSection\":[\"Aktuelles\"],\"inLanguage\":\"de\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/campuscontern.lu\\\/de\\\/aktuelles\\\/schulung-zur-kohlenstofffreien-mobilitaet-fuer-unsere-mieter-die-wichtigsten-erkenntnisse\\\/\",\"url\":\"https:\\\/\\\/campuscontern.lu\\\/de\\\/aktuelles\\\/schulung-zur-kohlenstofffreien-mobilitaet-fuer-unsere-mieter-die-wichtigsten-erkenntnisse\\\/\",\"name\":\"Schulung zur kohlenstofffreien Mobilit\u00e4t f\u00fcr unsere Mieter: Die wichtigsten Erkenntnisse - Campus Contern\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/campuscontern.lu\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/campuscontern.lu\\\/de\\\/aktuelles\\\/schulung-zur-kohlenstofffreien-mobilitaet-fuer-unsere-mieter-die-wichtigsten-erkenntnisse\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/campuscontern.lu\\\/de\\\/aktuelles\\\/schulung-zur-kohlenstofffreien-mobilitaet-fuer-unsere-mieter-die-wichtigsten-erkenntnisse\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/campuscontern.lu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/etiquette_article-3-2.png\",\"datePublished\":\"2022-12-05T15:44:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/campuscontern.lu\\\/de\\\/#\\\/schema\\\/person\\\/462336658fc158f425b7b47a82ece390\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/campuscontern.lu\\\/de\\\/aktuelles\\\/schulung-zur-kohlenstofffreien-mobilitaet-fuer-unsere-mieter-die-wichtigsten-erkenntnisse\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/campuscontern.lu\\\/de\\\/aktuelles\\\/schulung-zur-kohlenstofffreien-mobilitaet-fuer-unsere-mieter-die-wichtigsten-erkenntnisse\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/campuscontern.lu\\\/de\\\/aktuelles\\\/schulung-zur-kohlenstofffreien-mobilitaet-fuer-unsere-mieter-die-wichtigsten-erkenntnisse\\\/#primaryimage\",\"url\":\"https:\\\/\\\/campuscontern.lu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/etiquette_article-3-2.png\",\"contentUrl\":\"https:\\\/\\\/campuscontern.lu\\\/wp-content\\\/uploads\\\/2026\\\/04\\\/etiquette_article-3-2.png\",\"width\":1200,\"height\":628},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/campuscontern.lu\\\/de\\\/aktuelles\\\/schulung-zur-kohlenstofffreien-mobilitaet-fuer-unsere-mieter-die-wichtigsten-erkenntnisse\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/campuscontern.lu\\\/de\\\/startseite\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schulung zur kohlenstofffreien Mobilit\u00e4t f\u00fcr unsere Mieter: Die wichtigsten Erkenntnisse\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/campuscontern.lu\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/campuscontern.lu\\\/de\\\/\",\"name\":\"Campus Contern\",\"description\":\"Location bureaux Luxembourg\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/campuscontern.lu\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/campuscontern.lu\\\/de\\\/#\\\/schema\\\/person\\\/462336658fc158f425b7b47a82ece390\",\"name\":\"admin\",\"sameAs\":[\"https:\\\/\\\/campuscontern.lu\"],\"url\":\"https:\\\/\\\/campuscontern.lu\\\/de\\\/author\\\/markeasy\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Schulung zur kohlenstofffreien Mobilit\u00e4t f\u00fcr unsere Mieter: Die wichtigsten Erkenntnisse - Campus Contern","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"de_DE","og_type":"article","og_title":"Schulung zur kohlenstofffreien Mobilit\u00e4t f\u00fcr unsere Mieter: Die wichtigsten Erkenntnisse - Campus Contern","og_description":"Letzte Woche fand die erste Schulung \u201eStreben nach Kohlenstoffneutralit\u00e4t durch Mobilit\u00e4tsmanagement\u201c mit Luxmobility, Carbone 4, EIT Urban Mobility und IMS statt. Wir haben uns entschieden, unsere Mieter zur Teilnahme einzuladen. Hier sind die wichtigsten Punkte und Erkenntnisse, die wir daraus gewonnen haben: &nbsp; Einige aussagekr\u00e4ftige Zahlen: Der durchschnittliche CO2-Fu\u00dfabdruck eines Luxemburgers betr\u00e4gt 16 t CO2 [&hellip;]","og_url":"https:\/\/campuscontern.lu\/de\/aktuelles\/schulung-zur-kohlenstofffreien-mobilitaet-fuer-unsere-mieter-die-wichtigsten-erkenntnisse\/","og_site_name":"Campus Contern","article_published_time":"2022-12-05T15:44:58+00:00","og_image":[{"width":1200,"height":628,"url":"https:\/\/campuscontern.lu\/wp-content\/uploads\/2026\/04\/etiquette_article-3-2.png","type":"image\/png"}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"admin","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/campuscontern.lu\/de\/aktuelles\/schulung-zur-kohlenstofffreien-mobilitaet-fuer-unsere-mieter-die-wichtigsten-erkenntnisse\/#article","isPartOf":{"@id":"https:\/\/campuscontern.lu\/de\/aktuelles\/schulung-zur-kohlenstofffreien-mobilitaet-fuer-unsere-mieter-die-wichtigsten-erkenntnisse\/"},"author":{"name":"admin","@id":"https:\/\/campuscontern.lu\/de\/#\/schema\/person\/462336658fc158f425b7b47a82ece390"},"headline":"Schulung zur kohlenstofffreien Mobilit\u00e4t f\u00fcr unsere Mieter: Die wichtigsten Erkenntnisse","datePublished":"2022-12-05T15:44:58+00:00","mainEntityOfPage":{"@id":"https:\/\/campuscontern.lu\/de\/aktuelles\/schulung-zur-kohlenstofffreien-mobilitaet-fuer-unsere-mieter-die-wichtigsten-erkenntnisse\/"},"wordCount":677,"image":{"@id":"https:\/\/campuscontern.lu\/de\/aktuelles\/schulung-zur-kohlenstofffreien-mobilitaet-fuer-unsere-mieter-die-wichtigsten-erkenntnisse\/#primaryimage"},"thumbnailUrl":"https:\/\/campuscontern.lu\/wp-content\/uploads\/2026\/04\/etiquette_article-3-2.png","articleSection":["Aktuelles"],"inLanguage":"de"},{"@type":"WebPage","@id":"https:\/\/campuscontern.lu\/de\/aktuelles\/schulung-zur-kohlenstofffreien-mobilitaet-fuer-unsere-mieter-die-wichtigsten-erkenntnisse\/","url":"https:\/\/campuscontern.lu\/de\/aktuelles\/schulung-zur-kohlenstofffreien-mobilitaet-fuer-unsere-mieter-die-wichtigsten-erkenntnisse\/","name":"Schulung zur kohlenstofffreien Mobilit\u00e4t f\u00fcr unsere Mieter: Die wichtigsten Erkenntnisse - Campus Contern","isPartOf":{"@id":"https:\/\/campuscontern.lu\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/campuscontern.lu\/de\/aktuelles\/schulung-zur-kohlenstofffreien-mobilitaet-fuer-unsere-mieter-die-wichtigsten-erkenntnisse\/#primaryimage"},"image":{"@id":"https:\/\/campuscontern.lu\/de\/aktuelles\/schulung-zur-kohlenstofffreien-mobilitaet-fuer-unsere-mieter-die-wichtigsten-erkenntnisse\/#primaryimage"},"thumbnailUrl":"https:\/\/campuscontern.lu\/wp-content\/uploads\/2026\/04\/etiquette_article-3-2.png","datePublished":"2022-12-05T15:44:58+00:00","author":{"@id":"https:\/\/campuscontern.lu\/de\/#\/schema\/person\/462336658fc158f425b7b47a82ece390"},"breadcrumb":{"@id":"https:\/\/campuscontern.lu\/de\/aktuelles\/schulung-zur-kohlenstofffreien-mobilitaet-fuer-unsere-mieter-die-wichtigsten-erkenntnisse\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/campuscontern.lu\/de\/aktuelles\/schulung-zur-kohlenstofffreien-mobilitaet-fuer-unsere-mieter-die-wichtigsten-erkenntnisse\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/campuscontern.lu\/de\/aktuelles\/schulung-zur-kohlenstofffreien-mobilitaet-fuer-unsere-mieter-die-wichtigsten-erkenntnisse\/#primaryimage","url":"https:\/\/campuscontern.lu\/wp-content\/uploads\/2026\/04\/etiquette_article-3-2.png","contentUrl":"https:\/\/campuscontern.lu\/wp-content\/uploads\/2026\/04\/etiquette_article-3-2.png","width":1200,"height":628},{"@type":"BreadcrumbList","@id":"https:\/\/campuscontern.lu\/de\/aktuelles\/schulung-zur-kohlenstofffreien-mobilitaet-fuer-unsere-mieter-die-wichtigsten-erkenntnisse\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/campuscontern.lu\/de\/startseite\/"},{"@type":"ListItem","position":2,"name":"Schulung zur kohlenstofffreien Mobilit\u00e4t f\u00fcr unsere Mieter: Die wichtigsten Erkenntnisse"}]},{"@type":"WebSite","@id":"https:\/\/campuscontern.lu\/de\/#website","url":"https:\/\/campuscontern.lu\/de\/","name":"Campus Contern","description":"Location bureaux Luxembourg","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/campuscontern.lu\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Person","@id":"https:\/\/campuscontern.lu\/de\/#\/schema\/person\/462336658fc158f425b7b47a82ece390","name":"admin","sameAs":["https:\/\/campuscontern.lu"],"url":"https:\/\/campuscontern.lu\/de\/author\/markeasy\/"}]}},"_links":{"self":[{"href":"https:\/\/campuscontern.lu\/de\/wp-json\/wp\/v2\/posts\/13006","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/campuscontern.lu\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/campuscontern.lu\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/campuscontern.lu\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/campuscontern.lu\/de\/wp-json\/wp\/v2\/comments?post=13006"}],"version-history":[{"count":0,"href":"https:\/\/campuscontern.lu\/de\/wp-json\/wp\/v2\/posts\/13006\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/campuscontern.lu\/de\/wp-json\/wp\/v2\/media\/13007"}],"wp:attachment":[{"href":"https:\/\/campuscontern.lu\/de\/wp-json\/wp\/v2\/media?parent=13006"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/campuscontern.lu\/de\/wp-json\/wp\/v2\/categories?post=13006"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/campuscontern.lu\/de\/wp-json\/wp\/v2\/tags?post=13006"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}